{"id":1054,"date":"2023-07-29T11:46:08","date_gmt":"2023-07-29T09:46:08","guid":{"rendered":"https:\/\/ipsmonitor.de\/?page_id=1054"},"modified":"2023-10-02T05:26:19","modified_gmt":"2023-10-02T03:26:19","slug":"lagarosiphon-major","status":"publish","type":"page","link":"https:\/\/ipsmonitor.de\/en\/steckbriefe\/lagarosiphon-major\/","title":{"rendered":"Lagarosiphon major"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-25px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-right:10%;--awb-padding-left:10%;--awb-bg-blend:overlay;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1 fusion-text-no-margin\" style=\"--awb-margin-top:-20px;--awb-margin-bottom:-60px;\"><h3 style=\"text-align: center;\">Lagarosiphon major<\/h3>\n<\/div><div class=\"fusion-text fusion-text-2\"><h6 style=\"text-align: center;\">Curly Waterweed<\/h6>\n<\/div><div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1 lightbox-enabled fusion-carousel-border\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel\" data-autoplay=\"no\" data-columns=\"3\" data-itemmargin=\"50\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-imagesize=\"auto\" data-scrollitems=\"1\" style=\"--awb-columns:3;--awb-column-spacing:50px;\"><div class=\"swiper-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"Photo by: Dr Mary Gillham Archive Project. https:\/\/commons.wikimedia.org\/wiki\/File:Lagarosiphon_major._Howardian,_1992_(30491279833).jpg\" data-title=\"Lagarosiphon_1\" aria-label=\"Lagarosiphon_1\" href=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1.jpg\" target=\"_self\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1-200x150.jpg 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1-400x300.jpg 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1-600x450.jpg 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_1-1.jpg 800w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 367px, (min-width: 712px) 550px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"Photo by: Dr Mary Gillham Archive Project. https:\/\/commons.wikimedia.org\/wiki\/File:Lagarosiphon_majus,_Danydarren_Quarry_pool,_Cefn_Coed,_1994_(29296982852).jpg\" data-title=\"Lagarosiphon_2\" aria-label=\"Lagarosiphon_2\" href=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1.jpg\" target=\"_self\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1-200x150.jpg 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1-400x300.jpg 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1-600x450.jpg 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_2-1.jpg 800w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 367px, (min-width: 712px) 550px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-none\"><a data-rel=\"iLightbox[image_carousel_1]\" data-caption=\"Photo by: Christian Ferrer. https:\/\/commons.wikimedia.org\/wiki\/File:Lagarosiphon_major_flowers_on_Salagou_Lake_cf01.jpg\" data-title=\"Lagarosiphon_3\" aria-label=\"Lagarosiphon_3\" href=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3.jpg\" target=\"_self\"><img decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3-200x150.jpg 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3-400x300.jpg 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3-600x450.jpg 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/Lagarosiphon_3.jpg 800w\" sizes=\"(min-width: 2200px) 100vw, (min-width: 784px) 367px, (min-width: 712px) 550px, (min-width: 640px) 712px, \" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-padding-right:10%;--awb-padding-left:10%;--awb-bg-color:#ffffff;--awb-bg-image:radial-gradient(circle at center center, #ffffff 35%,rgba(255,255,255,0) 71%);;--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-3\" style=\"--awb-line-height:1.5;\"><p style=\"text-align: center;\">Lagarosiphon major is a submerged aquatic plant that originates from South Africa. The plant can grow up to 5 metres long and forms dense mats on the water surface. L. major is characterised by its dense, spirally arranged leaves, which are around 1 cm long and pointed. The plant rarely flowers and when it does, it is usually only on the water surface. The flowers are small and white, with the female flowers remaining on the plant and the male flowers drifting off at the surface. Reproduction is primarily vegetative, with individual plant parts breaking off to form new plants. It prefers stagnant and slow-flowing waters and is tolerant of changing environmental conditions, including different water temperatures and qualities. In Europe and other parts of the world where it has been introduced, it can spread rapidly and quickly forms large carpets on the water surface, competing with native aquatic plants and disturbing the ecological balance of water bodies.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-4\"><h5 style=\"text-align: center;\">Types of damage<\/h5>\n<\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-2 fusion-content-boxes-1 content-boxes-icon-on-side content-left\" style=\"--awb-item-margin-top:0px;--awb-item-margin-bottom:0px;--awb-margin-bottom:-px;--awb-hover-accent-color:#000000;--awb-circle-hover-accent-color:#000000;--awb-item-margin-bottom:40px;\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-none\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/05\/ecology1.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Ecological damage<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-1\"><div class=\"fusion-panel panel-default panel-33b3540413c4516ca fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_33b3540413c4516ca\"><a aria-expanded=\"false\" aria-controls=\"33b3540413c4516ca\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-1\" data-target=\"#33b3540413c4516ca\" href=\"#33b3540413c4516ca\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Suppression of native species<\/span><\/a><\/h4><\/div><div id=\"33b3540413c4516ca\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_33b3540413c4516ca\"><div class=\"panel-body toggle-content fusion-clearfix\">\nDue to its rapid reproduction and spread, Lagarosiphon major can dominate aquatic habitats and suppress native aquatic flora, leading to a reduction in biodiversity. In addition, its dense growth can block the light necessary for the growth of other aquatic organisms, thus disrupting the entire ecosystem of the water body.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-none\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/05\/euro1.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Economical damage<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-2\"><div class=\"fusion-panel panel-default panel-b7c6a55b07807623e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_b7c6a55b07807623e\"><a aria-expanded=\"false\" aria-controls=\"b7c6a55b07807623e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-2\" data-target=\"#b7c6a55b07807623e\" href=\"#b7c6a55b07807623e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Impairment of water areas<\/span><\/a><\/h4><\/div><div id=\"b7c6a55b07807623e\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_b7c6a55b07807623e\"><div class=\"panel-body toggle-content fusion-clearfix\">\nLagarosiphon major can block waterways, disrupting water traffic and transport. In addition, it can interfere with recreational use of water bodies such as fishing, swimming and boating. The costs of controlling and eradicating this invasive species can be significant.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-center fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\"><h5 style=\"text-align: center;\">Region of origin<\/h5>\n<\/div><div class=\"fusion-text fusion-text-6\" style=\"--awb-margin-top:-20px;\"><p style=\"text-align: center;\">Southern Africa<\/p>\n<\/div><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-1 hover-type-none\"><img decoding=\"async\" width=\"295\" height=\"295\" title=\"southern_africa\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/southern_africa.png\" alt class=\"img-responsive wp-image-1056\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/southern_africa-200x200.png 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/southern_africa.png 295w\" sizes=\"(max-width: 640px) 100vw, 295px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-7\"><h5 style=\"text-align: center;\">Introduction vectors<\/h5>\n<\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-2 fusion-content-boxes-2 content-boxes-icon-on-side content-left\" style=\"--awb-item-margin-bottom:;--awb-margin-bottom:-px;--awb-hover-accent-color:var(--awb-color4);--awb-circle-hover-accent-color:var(--awb-color4);\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-fade\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/06\/horticulture.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Horticulture<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">Although Lagarosiphon major is mainly traded as an aquatic plant, it can also be accidentally spread with other garden plants when garden waste containing remnants of the plant is disposed of near waterways.<\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-fade\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/fish.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Pet trade (aquaristics)<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\">Lagarosiphon major is a popular aquatic plant and was often bought for aquariums and garden ponds in the past. From there it could enter the environment when the aquarium or pond was cleaned or drained and remnants of the plant got into nearby waterways<\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-8\"><h5 style=\"text-align: center;\">Current distribution<\/h5>\n<\/div><div class=\"fusion-text fusion-text-9\" style=\"--awb-margin-top:-20px;\"><p style=\"text-align: center;\">Based on the <a href=\"https:\/\/www.floraweb.de\/xsql\/artenhome.xsql?suchnr=371&amp;\">FlorKart<\/a> Database of the Federal Agency for Nature Conservation, as of 2013<\/p>\n<\/div><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-2 hover-type-none\"><a class=\"fusion-no-lightbox\" href=\"https:\/\/www.floraweb.de\/webkarten\/karte.html?taxnr=3252\" target=\"_blank\" aria-label=\"s_3252_Lagarosiphon\" rel=\"noopener noreferrer\"><img decoding=\"async\" width=\"222\" height=\"300\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon-222x300.png\" alt class=\"img-responsive wp-image-1058\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon-200x270.png 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon-400x541.png 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon-600x811.png 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon-800x1081.png 800w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/s_3252_Lagarosiphon.png 874w\" sizes=\"(max-width: 640px) 100vw, 400px\" \/><\/a><\/span><\/div><div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-left:20px;--awb-max-width:225px;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-3 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"31\" title=\"legende2_eng\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng.png\" alt class=\"img-responsive wp-image-250\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng-18x2.png 18w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng-200x21.png 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng-300x31.png 300w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng-400x41.png 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng-600x62.png 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende2_eng.png 667w\" sizes=\"(max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-10\"><h5 style=\"text-align: center;\">Miscellaneous<\/h5>\n<\/div><div class=\"fusion-content-boxes content-boxes columns row fusion-columns-1 fusion-columns-total-2 fusion-content-boxes-3 content-boxes-icon-on-side content-left\" style=\"--awb-item-margin-bottom:0px;--awb-margin-bottom:-px;--awb-hover-accent-color:#000000;--awb-circle-hover-accent-color:#000000;--awb-item-margin-bottom:40px;\" data-animationoffset=\"top-into-view\"><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-1 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-none\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/05\/ecology1.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Family<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-3\"><div class=\"fusion-panel panel-default panel-0cfb4e189b287ae0e fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_0cfb4e189b287ae0e\"><a aria-expanded=\"false\" aria-controls=\"0cfb4e189b287ae0e\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-3\" data-target=\"#0cfb4e189b287ae0e\" href=\"#0cfb4e189b287ae0e\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Hydrocharitaceae<\/span><\/a><\/h4><\/div><div id=\"0cfb4e189b287ae0e\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_0cfb4e189b287ae0e\"><div class=\"panel-body toggle-content fusion-clearfix\">\nThe Hydrocharitaceae comprise about 16 genera with about 135 species. They are distributed worldwide and represent the largest family of fully aquatic flowering plants. The family includes both free-floating and bottom-anchored species, which can often form dense stands. Characteristic features are the mostly simple, often linear leaves and the often small, inconspicuous flowers. Many species are important for the ecosystem of freshwaters, but some can also cause problems as invasive plants. Well-known representatives are the hornwort (Ceratophyllum), or the waterweed (Elodea), which are used as aquarium plants.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div style=\"--awb-backgroundcolor:rgba(255,255,255,0);--awb-content-padding-left:95px;\" class=\"fusion-column content-box-column content-box-column content-box-column-2 col-lg-12 col-md-12 col-sm-12 fusion-content-box-hover content-box-column-last content-box-column-last-in-row\"><div class=\"col content-box-wrapper content-wrapper link-area-link-icon content-icon-wrapper-yes icon-hover-animation-none\" data-animationoffset=\"top-into-view\"><div class=\"heading heading-with-icon icon-left\"><div aria-hidden=\"true\" class=\"image\"><img decoding=\"async\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/sun.png\" width=\"75\" height=\"75\" alt=\"\" \/><\/div><h1 class=\"content-box-heading\" style=\"--h1_typography-font-size:20px;line-height:25px;padding-left:95px;\">Climate change<\/h1><\/div><div class=\"fusion-clearfix\"><\/div><div class=\"content-container\"><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-4\"><div class=\"fusion-panel panel-default panel-0e8ac2f1361e79099 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_0e8ac2f1361e79099\"><a aria-expanded=\"false\" aria-controls=\"0e8ac2f1361e79099\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-4\" data-target=\"#0e8ac2f1361e79099\" href=\"#0e8ac2f1361e79099\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">Does not benefit from climate change<\/span><\/a><\/h4><\/div><div id=\"0e8ac2f1361e79099\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_0e8ac2f1361e79099\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>Lagarosiphon major has not yet filled its potentially suitable habitat under current climate conditions. It does not benefit from climate change because in the future its potentially suitable habitat will become smaller. The environmental factors that most influence its dispersal are waterways, soil type, land use type, altitude and annual temperature.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-11\"><h5 style=\"text-align: center;\">Dispersion forecast<\/h5>\n<\/div><div class=\"fusion-text fusion-text-12\" style=\"--awb-margin-top:-20px;\"><p style=\"text-align: center;\">Indicates the proportion of land suitable for habitat under current and future climate conditions (2060-2080) under three emission scenarios (RCP26, RCP45 &amp; RCP85).<\/p>\n<\/div><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-4 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"245\" title=\"proportion_Lagarosiph_3252\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252-300x245.png\" alt class=\"img-responsive wp-image-1060\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252-200x163.png 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252-400x326.png 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252-600x489.png 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252-800x652.png 800w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/07\/proportion_Lagarosiph_3252.png 823w\" sizes=\"(max-width: 640px) 100vw, 400px\" \/><\/span><\/div><div class=\"fusion-image-element\" style=\"text-align:center;--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\"fusion-imageframe imageframe-none imageframe-5 hover-type-none\"><img decoding=\"async\" width=\"300\" height=\"40\" title=\"legende_eng\" src=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng.jpg\" alt class=\"img-responsive wp-image-234\" srcset=\"https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-18x2.jpg 18w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-200x26.jpg 200w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-300x40.jpg 300w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-400x53.jpg 400w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-600x79.jpg 600w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-768x101.jpg 768w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-800x106.jpg 800w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng-1024x135.jpg 1024w, https:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/legende_eng.jpg 1052w\" sizes=\"(max-width: 640px) 100vw, 400px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start\" style=\"max-width:1248px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-8 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:-20px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-separator fusion-full-width-sep\" style=\"align-self: center;margin-left: auto;margin-right: auto;flex-grow:2;margin-top:50px;width:100%;max-width:100%;\"><div class=\"fusion-separator-border sep-shadow\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#000000;background:radial-gradient(ellipse at 50% -50% , #000000 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-webkit-radial-gradient(ellipse at 50% -50% , #000000 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-moz-radial-gradient(ellipse at 50% -50% , #000000 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);background:-o-radial-gradient(ellipse at 50% -50% , #000000 0px, rgba(255, 255, 255, 0) 80%) repeat scroll 0 0 rgba(0, 0, 0, 0);\"><\/div><\/div><div class=\"fusion-title title fusion-title-1 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-four\" style=\"--awb-margin-top:40px;\"><h4 class=\"title-heading-center\" style=\"margin:0;\"><p style=\"text-align: center;\">Habitat suitability maps<\/p><\/h4><\/div><div class=\"fusion-text fusion-text-13\"><p style=\"text-align: center;\">Instructions for use: <span style=\"color: #02836c;\"><a style=\"color: #02836c;\" href=\"http:\/\/ipsmonitor.de\/wp-content\/uploads\/2023\/09\/Map_Tutorial_eng.jpg\" target=\"_blank\" rel=\"noopener\"><u><strong>Click here<\/strong><\/u><\/a><\/span><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-9 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.6666666667%;--awb-margin-top-large:-10px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:66.6666666667%;--awb-order-medium:0;--awb-spacing-right-medium:2.88%;--awb-spacing-left-medium:2.88%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-14\"><style type=\"text\/css\">\r\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe = 0;var ai_iframe_height_advanced_iframe = 0;var aiIsIe8=false;var aiOnloadScrollTop=\"iframe\";var aiShowDebug=false;\r\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\r\n\t\t\tvar aiReadyCallbacks = [];  \r\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\r\n\t\t\tvar aiReadyCallbacks = [];\r\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe\"  name=\"advanced_iframe\"  src=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_pre.html\"  width=\"100%\"  height=\"600\"  scrolling=\"no\"  frameborder=\"0\"  allowtransparency=\"true\"  loading=\"auto\"  style=\"border: 3px solid #02836c;;width:100%;height:600px;\"  onload='aiScrollToTop(&quot;advanced_iframe&quot;,&quot;iframe&quot;)' ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe = document.getElementById(\"advanced_iframe\");var hiddenTabsDoneadvanced_iframe = false;\r\nfunction resizeCallbackadvanced_iframe() {}<\/script><script type=\"text\/javascript\"><\/script>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-10 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:-10px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-15\"><h5 style=\"text-align: center;\">Habitat suitability under current climate conditions<\/h5>\n<\/div><div class=\"fusion-text fusion-text-16\"><p>These habitat suitability maps show for <strong>Lagarosiphon major<\/strong> where suitable habitat conditions exist.<\/p>\n<p>The map on the left shows this for current climate conditions. Below this are maps for the time classes 2040-2060 and 2061-2080, in which three different emission scenarios can be selected.<\/p>\n<p>The slider at the top left allows you to adjust the opacity of the map to make orientation easier.<\/p>\n<p>By clicking on the respective quadrant, information on the environmental conditions present in it can be called up.<\/p>\n<p class=\" translation-block\">The methodology is explained <a href=\"https:\/\/ipsmonitor.de\/methoden\/\" target=\"_blank\" rel=\"noopener\"><strong>here <\/strong><\/a>.<\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--button_margin-top:50px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_pre_eng.html\"><span class=\"fusion-button-text\">Open in larger window<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-11 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-17\"><h5 style=\"text-align: center;\">Habitat suitability 2040 - 2060<\/h5>\n<\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-5\"><div class=\"fusion-panel panel-default panel-be5c0e90c7e82567a fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_be5c0e90c7e82567a\"><a aria-expanded=\"false\" aria-controls=\"be5c0e90c7e82567a\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-5\" data-target=\"#be5c0e90c7e82567a\" href=\"#be5c0e90c7e82567a\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 2.6<\/span><\/a><\/h4><\/div><div id=\"be5c0e90c7e82567a\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_be5c0e90c7e82567a\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>2040-2060: In the RCP2.6 scenario, GHG emissions are expected to peak by 2040 through comprehensive mitigation measures and to decline rapidly thereafter. By 2060, global warming would stabilise at about 1.5\u00b0C above pre-industrial levels. Subtle changes in precipitation patterns could vary regionally, with some areas facing increased drought and others increased precipitation.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-ac65e7e9c9a93fd54 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_ac65e7e9c9a93fd54\"><a aria-expanded=\"false\" aria-controls=\"ac65e7e9c9a93fd54\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-5\" data-target=\"#ac65e7e9c9a93fd54\" href=\"#ac65e7e9c9a93fd54\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 4.5<\/span><\/a><\/h4><\/div><div id=\"ac65e7e9c9a93fd54\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_ac65e7e9c9a93fd54\"><div class=\"panel-body toggle-content fusion-clearfix\">2040-2060: Under RCP4.5, GHG emissions would continue to increase until 2040, but stabilise at a high level thereafter. By 2060, there could be a global temperature increase of about 2\u00b0C above pre-industrial levels. This scenario would likely cause moderate changes in precipitation patterns, with potential regional differences.<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-3da8cb5158a9367ff fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_3da8cb5158a9367ff\"><a aria-expanded=\"false\" aria-controls=\"3da8cb5158a9367ff\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-5\" data-target=\"#3da8cb5158a9367ff\" href=\"#3da8cb5158a9367ff\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 8.5<\/span><\/a><\/h4><\/div><div id=\"3da8cb5158a9367ff\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_3da8cb5158a9367ff\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>2040-2060: Under RCP8.5, which assumes continued intensive use of fossil fuels, greenhouse gas emissions would rise sharply by 2060. The global temperature increase could be around 2.5-3\u00b0C. In this scenario, significant changes in precipitation patterns could occur, with an increased likelihood of extreme weather events.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-2 fusion-button-default-span fusion-button-default-type\" style=\"--button_margin-top:50px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_tc1_eng.html\"><span class=\"fusion-button-text\">Open in larger window<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-12 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.6666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:66.6666666667%;--awb-order-medium:0;--awb-spacing-right-medium:2.88%;--awb-spacing-left-medium:2.88%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-18\"><style type=\"text\/css\">\r\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe_2 {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe_2 p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe_2 = 0;var ai_iframe_height_advanced_iframe_2 = 0;var aiIsIe8=false;var aiOnloadScrollTop=\"iframe\";var aiShowDebug=false;\r\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\r\n\t\t\tvar aiReadyCallbacks = [];  \r\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\r\n\t\t\tvar aiReadyCallbacks = [];\r\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe_2); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe_2\"  name=\"advanced_iframe_2\"  src=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_tc1.html\"  width=\"100%\"  height=\"600\"  scrolling=\"no\"  frameborder=\"0\"  allowtransparency=\"true\"  loading=\"auto\"  style=\"border: 3px solid #02836c;;width:100%;height:600px;\"  onload='aiScrollToTop(&quot;advanced_iframe_2&quot;,&quot;iframe&quot;)' ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe_2 = document.getElementById(\"advanced_iframe_2\");var hiddenTabsDoneadvanced_iframe_2 = false;\r\nfunction resizeCallbackadvanced_iframe_2() {}<\/script><script type=\"text\/javascript\"><\/script>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-13 fusion_builder_column_2_3 2_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:66.6666666667%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.88%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.88%;--awb-width-medium:66.6666666667%;--awb-order-medium:0;--awb-spacing-right-medium:2.88%;--awb-spacing-left-medium:2.88%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-19\"><style type=\"text\/css\">\r\n       .errordiv { padding:10px; margin:10px; border: 1px solid #555555;color: #000000;background-color: #f8f8f8; width:500px; }#advanced_iframe_3 {visibility:visible;opacity:1;vertical-align:top;}.ai-info-bottom-iframe { position: fixed; z-index: 10000; bottom:0; left: 0; margin: 0px; text-align: center; width: 100%; background-color: #ff9999; padding-left: 5px;padding-bottom: 5px; border-top: 1px solid #aaa } a.ai-bold {font-weight: bold;}#ai-layer-div-advanced_iframe_3 p {height:100%;margin:0;padding:0}<\/style><script type=\"text\/javascript\">var ai_iframe_width_advanced_iframe_3 = 0;var ai_iframe_height_advanced_iframe_3 = 0;var aiIsIe8=false;var aiOnloadScrollTop=\"iframe\";var aiShowDebug=false;\r\n\t\tif (typeof aiReadyCallbacks === 'undefined') {\r\n\t\t\tvar aiReadyCallbacks = [];  \r\n\t\t} else if (!(aiReadyCallbacks instanceof Array)) {\r\n\t\t\tvar aiReadyCallbacks = [];\r\n\t\t}    function aiShowIframeId(id_iframe) { jQuery(\"#\"+id_iframe).css(\"visibility\", \"visible\");    }    function aiResizeIframeHeight(height) { aiResizeIframeHeight(height,advanced_iframe_3); }    function aiResizeIframeHeightId(height,width,id) {aiResizeIframeHeightById(id,height);}<\/script><iframe id=\"advanced_iframe_3\"  name=\"advanced_iframe_3\"  src=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_tc2.html\"  width=\"100%\"  height=\"600\"  scrolling=\"no\"  frameborder=\"0\"  allowtransparency=\"true\"  loading=\"auto\"  style=\"border: 3px solid #02836c;;width:100%;height:600px;\"  onload='aiScrollToTop(&quot;advanced_iframe_3&quot;,&quot;iframe&quot;)' ><\/iframe><script type=\"text\/javascript\">var ifrm_advanced_iframe_3 = document.getElementById(\"advanced_iframe_3\");var hiddenTabsDoneadvanced_iframe_3 = false;\r\nfunction resizeCallbackadvanced_iframe_3() {}<\/script><script type=\"text\/javascript\"><\/script>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-14 fusion_builder_column_1_3 1_3 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:33.3333333333%;--awb-margin-top-large:0px;--awb-spacing-right-large:5.76%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:5.76%;--awb-width-medium:33.3333333333%;--awb-order-medium:0;--awb-spacing-right-medium:5.76%;--awb-spacing-left-medium:5.76%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-20\"><h5 style=\"text-align: center;\">Habitat suitability 2061 - 2080<\/h5>\n<\/div><div class=\"accordian fusion-accordian\" style=\"--awb-border-size:1px;--awb-icon-size:16px;--awb-content-font-size:var(--awb-typography4-font-size);--awb-icon-alignment:left;--awb-hover-color:var(--awb-color2);--awb-border-color:var(--awb-color3);--awb-background-color:var(--awb-color1);--awb-divider-color:var(--awb-color3);--awb-divider-hover-color:var(--awb-color3);--awb-icon-color:var(--awb-color1);--awb-title-color:var(--awb-color8);--awb-content-color:var(--awb-color8);--awb-icon-box-color:var(--awb-color8);--awb-toggle-hover-accent-color:var(--awb-color5);--awb-title-font-family:var(--awb-typography1-font-family);--awb-title-font-weight:var(--awb-typography1-font-weight);--awb-title-font-style:var(--awb-typography1-font-style);--awb-title-font-size:16px;--awb-content-font-family:var(--awb-typography4-font-family);--awb-content-font-weight:var(--awb-typography4-font-weight);--awb-content-font-style:var(--awb-typography4-font-style);\"><div class=\"panel-group fusion-toggle-icon-boxed\" id=\"accordion-1054-6\"><div class=\"fusion-panel panel-default panel-eb9fd332998d7e389 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_eb9fd332998d7e389\"><a aria-expanded=\"false\" aria-controls=\"eb9fd332998d7e389\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-6\" data-target=\"#eb9fd332998d7e389\" href=\"#eb9fd332998d7e389\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 2.6<\/span><\/a><\/h4><\/div><div id=\"eb9fd332998d7e389\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_eb9fd332998d7e389\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>2060-2080: By 2080, global warming could be limited to below 2\u00b0C in the RCP2.6 scenario, provided emission reductions are consistently pursued. Impacts on precipitation patterns would likely stabilise, although regional variance would remain significant.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-748ddf5fcb8805057 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_748ddf5fcb8805057\"><a aria-expanded=\"false\" aria-controls=\"748ddf5fcb8805057\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-6\" data-target=\"#748ddf5fcb8805057\" href=\"#748ddf5fcb8805057\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 4.5<\/span><\/a><\/h4><\/div><div id=\"748ddf5fcb8805057\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_748ddf5fcb8805057\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>2060-2080: In the RCP4.5 scenario, global temperatures would continue to increase and could be around 2.5\u00b0C above pre-industrial levels by 2080. Changes in precipitation patterns would likely increase and regional differences could become more pronounced.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-panel panel-default panel-f87f474cbe67a9619 fusion-toggle-has-divider\"><div class=\"panel-heading\"><h4 class=\"panel-title toggle\" id=\"toggle_f87f474cbe67a9619\"><a aria-expanded=\"false\" aria-controls=\"f87f474cbe67a9619\" role=\"button\" data-toggle=\"collapse\" data-parent=\"#accordion-1054-6\" data-target=\"#f87f474cbe67a9619\" href=\"#f87f474cbe67a9619\"><span class=\"fusion-toggle-icon-wrapper\" aria-hidden=\"true\"><i class=\"fa-fusion-box active-icon awb-icon-minus\" aria-hidden=\"true\"><\/i><i class=\"fa-fusion-box inactive-icon awb-icon-plus\" aria-hidden=\"true\"><\/i><\/span><span class=\"fusion-toggle-heading\">RCP 8.5<\/span><\/a><\/h4><\/div><div id=\"f87f474cbe67a9619\" class=\"panel-collapse collapse\" araia-labelledby=\"toggle_f87f474cbe67a9619\"><div class=\"panel-body toggle-content fusion-clearfix\">\n<p>2060-2080: Under RCP8.5, global temperatures could rise by more than 4\u00b0C above pre-industrial levels by 2080. Precipitation patterns would be expected to change significantly, with further increases in the frequency and intensity of extreme weather events. This would have far-reaching impacts on ecological and socio-economic systems.<\/p>\n<\/div><\/div><\/div><\/div><\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat fusion-button-default-size button-default fusion-button-default button-3 fusion-button-default-span fusion-button-default-type\" style=\"--button_margin-top:50px;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/ipsmonitor.de\/HSM\/s_3252\/h_s3252_tc2_eng.html\"><span class=\"fusion-button-text\">Open in larger window<\/span><\/a><\/div><\/div><\/div><\/div><\/div><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":137,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-1054","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/pages\/1054","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/comments?post=1054"}],"version-history":[{"count":6,"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/pages\/1054\/revisions"}],"predecessor-version":[{"id":1427,"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/pages\/1054\/revisions\/1427"}],"up":[{"embeddable":true,"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/pages\/137"}],"wp:attachment":[{"href":"https:\/\/ipsmonitor.de\/en\/wp-json\/wp\/v2\/media?parent=1054"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}